{"id":4309,"date":"2023-03-28T14:59:43","date_gmt":"2023-03-28T12:59:43","guid":{"rendered":"https:\/\/relaismanderen.com\/?page_id=4309"},"modified":"2025-03-05T13:44:06","modified_gmt":"2025-03-05T12:44:06","slug":"rechtliche-hinweise","status":"publish","type":"page","link":"https:\/\/relaismanderen.com\/de\/rechtliche-hinweise\/","title":{"rendered":"Rechtliche Hinweise"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4309\" class=\"elementor elementor-4309\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a0cc2ca elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a0cc2ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 2600 131.1\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21fcce31\" data-id=\"21fcce31\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ca5fcaa elementor-widget__width-inherit elementor-widget elementor-widget-hoteller-animated-text\" data-id=\"1ca5fcaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-left transition-right overflow-visible\" data-delimiter=\"character\" data-transition=\"50\" data-transition-delay=\"0\" data-transition-duration=\"800\">\n\t\t<h2>\n\t\tErw\u00e4hnungen\t<\/h2>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cf0e361 elementor-widget__width-inherit elementor-widget elementor-widget-hoteller-animated-text\" data-id=\"6cf0e361\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"hoteller-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-left transition-right overflow-visible\" data-delimiter=\"character\" data-transition=\"50\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<h2>\n\t\tLegale\t<\/h2>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6061604 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6061604\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2e7af5\" data-id=\"f2e7af5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0386624 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0386624\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;hoteller_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_backdrop&quot;:&quot;false&quot;,&quot;hoteller_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-850877a\" data-id=\"850877a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28499ea elementor-widget elementor-widget-text-editor\" data-id=\"28499ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hoteller_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;hoteller_ext_is_scrollme&quot;:&quot;false&quot;,&quot;hoteller_ext_is_smoove&quot;:&quot;false&quot;,&quot;hoteller_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;hoteller_ext_is_infinite&quot;:&quot;false&quot;,&quot;hoteller_ext_is_fadeout_animation&quot;:&quot;false&quot;,&quot;hoteller_ext_mobile_static&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"bk-content-text js-text-content wysihtml-editor-content\"><p class=\"p1\"><span class=\"s1\">Verantwortlich f\u00fcr die Ver\u00f6ffentlichung: Frau LEMOINE<\/span><\/p><p class=\"p1\"><span class=\"s1\">Name der Betreibergesellschaft : RELAIS MANDEREN GMBH<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Individuelle Umsatzsteuer-Identifikationsnummer: FR01919081851<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Siret-Nummer:91908185100017<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Gesellschaftskapital: 5000\u20ac<\/span><\/p><p class=\"p1\"><span class=\"s1\">INFORMATIK UND FREIHEIT<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Jeder Nutzer, der direkt oder indirekt namentliche Informationen hinterlegt hat, hat gem\u00e4\u00df dem Gesetz Nr. 7817 vom 6\/01\/78 (Informatique et Libert\u00e9) ein Recht auf Zugang und Berichtigung beim Administrator der Website.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Hyperlinks<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Websites au\u00dferhalb von RELAIS MANDEREN SARL, die einen Hyperlink zu dieser Website haben, stehen nicht unter der Kontrolle von RELAIS MANDEREN SARL , die folglich jegliche Verantwortung f\u00fcr deren Inhalt ablehnt. Der Nutzer ist allein f\u00fcr die Nutzung dieser Links verantwortlich.<\/span><\/p><p class=\"p2\"><span class=\"s1\">VERANTWORTUNG<\/span><\/p><p class=\"p1\"><span class=\"s1\">RELAIS MANDEREN SARL kann nicht f\u00fcr Fehler oder Auslassungen haftbar gemacht werden, da sich der Herausgeber das Recht vorbeh\u00e4lt, die Daten auf der Website jederzeit zu \u00e4ndern und zu aktualisieren.<\/span><\/p><p class=\"p2\"><span class=\"s1\">COPYRIGHT<\/span><\/p><p class=\"p1\"><span class=\"s1\">Gem\u00e4\u00df dem franz\u00f6sischen Gesetz \u00fcber geistiges Eigentum ist f\u00fcr die teilweise oder vollst\u00e4ndige Vervielf\u00e4ltigung der Daten (Layout, Anordnung der Website, Fotos, Texte und Illustrationen, die durch das Urheberrecht gesch\u00fctzt sind) f\u00fcr eine andere als private Nutzung, den Verkauf, die Verbreitung, die Ver\u00f6ffentlichung, die Anpassung oder die Kommunikation die vorherige schriftliche Genehmigung der Inhaber der oben genannten Rechte erforderlich.<\/span><\/p><p class=\"p2\"><span class=\"s1\">INFORMATIK UND FREIHEITSRECHTE<\/span><\/p><p class=\"p1\"><span class=\"s1\">Jeder Nutzer, der direkt oder indirekt namentliche Informationen hinterlegt hat, hat gem\u00e4\u00df dem Gesetz Nr. 7817 vom 6\/01\/78 (Informatique et Libert\u00e9s) ein Recht auf Zugang und Berichtigung beim Administrator der Website.<\/span><\/p><p class=\"p2\"><span class=\"s1\">SCHUTZ VON PERS\u00d6NLICHEN DATEN<\/span><\/p><p class=\"p3\"><span class=\"s1\">Identit\u00e4t des f\u00fcr die Verarbeitung Verantwortlichen<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Website wird von der Betreibergesellschaft herausgegeben, deren Kontaktdaten oben angegeben sind.<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Der Zugriff auf die Website und die Nutzung ihres Inhalts erfolgen im Rahmen der nachstehend beschriebenen Nutzungsbedingungen.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Art der pers\u00f6nlichen Daten<\/span><\/p><p class=\"p1\"><span class=\"s1\">Unter \"pers\u00f6nlichen Daten\" versteht man alle pers\u00f6nlichen Informationen, die Sie der Betreibergesellschaft mitteilen k\u00f6nnen und die es der Betreibergesellschaft erm\u00f6glichen k\u00f6nnen, Sie direkt oder indirekt als nat\u00fcrliche Person zu identifizieren, z. B. bei einem Besuch der Website, einer Informationsanfrage, einer Zimmerreservierung und anderen Leistungen.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Die gesammelten pers\u00f6nlichen Daten<\/span><\/p><p class=\"p1\"><span class=\"s1\">Sie k\u00f6nnen aufgefordert werden, Ihre pers\u00f6nlichen Daten anzugeben, wenn Sie auf der Website der Betreibergesellschaft surfen.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Ob die angeforderten Informationen obligatorisch oder fakultativ sind, wird Ihnen bei der Erhebung mit einem Sternchen \"*\" mitgeteilt. Die mit einem Sternchen gekennzeichneten Informationen sind obligatorisch, da sie f\u00fcr die Bearbeitung Ihrer verschiedenen Anfragen unerl\u00e4sslich sind. Die \u00fcbrigen Informationen dienen dazu, Sie besser kennen zu lernen und die Ihnen angebotenen Dienstleistungen zu verbessern. Sie sind daher freiwillig.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Betreibergesellschaft sammelt und verarbeitet insbesondere Ihren Namen, Vornamen, Ihre E-Mail-Adresse, Rechnungsadresse, Telefonnummer, IP-Adresse, Verbindungs- und Navigationsdaten, Ihre Vorlieben und Interessen (Nichtraucherzimmer, Lieblingszimmer, Art des Aufenthalts...), Ihre Online-Bewertungen.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Wann werden Ihre pers\u00f6nlichen Daten gesammelt?<\/span><\/p><ul class=\"ul1\"><li class=\"li4\"><span class=\"s1\">Sie surfen auf der Website (IP-Adresse und Cookies) und sehen sich Produkte oder Dienstleistungen an ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Sie teilen der Betreibergesellschaft Ihre Beobachtungen\/Kommentare in bestimmten Rubriken, \u00fcber Frageb\u00f6gen oder Kontaktformulare, offizielle Seite der sozialen Netzwerke der Betreibergesellschaft mit;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Sie senden der Betreibergesellschaft eine elektronische Nachricht ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Sie tragen sich in die Mailingliste des Newsletters ein ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Sie teilen eine Seite oder ein Angebot durch das Versenden einer E-Mail oder \u00fcber ein soziales Netzwerk ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Sie beantworten einen Fragebogen zur Zufriedenheit ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Sie stellen eine Anfrage f\u00fcr einen Kostenvoranschlag.<\/span><\/li><\/ul><p class=\"p3\"><span class=\"s1\">Die Speicherung von Daten<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die gesammelten Informationen werden in unseren verschiedenen Buchungssystemen in sicheren, SSL-zertifizierten Datenbanken gespeichert.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Diese Datenbank umfasst: die Namen der G\u00e4ste, ihre Adressen, Telefonnummern, ihre Position, den Namen ihres Unternehmens und die Daten ihrer Kreditkarten. Wir k\u00f6nnen auch andere Informationen speichern, wie z. B. Ihre Pr\u00e4ferenzen in Bezug auf Zimmer, Mahlzeiten, Getr\u00e4nke und andere Dienstleistungen sowie Ihren bisherigen Aufenthalt in unserer Einrichtung.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Zweck der Datenerhebung durch die Betreibergesellschaft<\/span><\/p><p class=\"p1\"><span class=\"s1\">\u00dcber die Website sammelt die Betreibergesellschaft Daten \u00fcber Sie, die f\u00fcr die folgenden Zwecke unbedingt erforderlich sind:<\/span><\/p><ol class=\"ol1\"><li class=\"li4\"><span class=\"s1\">Um Ihre Informations- und Buchungsanfragen sowie etwaige Treueprogramme zu verwalten ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Um die Dienste der Betreibergesellschaft zu verbessern und zu personalisieren, um Ihnen die Navigation auf der Website zu erleichtern ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Um die gesamte Kundenbeziehung zu verwalten und zu verfolgen ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Verwaltung der Anmeldung zu Neuigkeiten und Werbeangeboten der Betreibergesellschaft (Newsletter) ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Um alle Ihre Zugangsanfragen gem\u00e4\u00df den geltenden Gesetzen zu verwalten ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Verwalten von unbezahlten Rechnungen und Streitf\u00e4llen ;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Bewerbungen im Rahmen von Stellenangeboten des Betreiberunternehmens, die Ihre Aufmerksamkeit erregt haben, oder spontane Bewerbungen verwalten;<\/span><\/li><li class=\"li4\"><span class=\"s1\">Die Messung von Qualit\u00e4t und Zufriedenheit.<\/span><\/li><\/ol><p class=\"p1\"><span class=\"s1\">Wenn Sie die Pflichtangaben nicht beantworten, kann Ihre Anfrage nicht ber\u00fccksichtigt werden.<\/span><\/p><p class=\"p2\"><span class=\"s1\">Verpflichtungen der Betreibergesellschaft zum Schutz personenbezogener Daten<\/span><\/p><p class=\"p3\"><span class=\"s1\">Transparenz und Zweck :<\/span><\/p><p class=\"p1\"><span class=\"s1\">Es werden keine personenbezogenen Daten ohne Ihr Wissen gesammelt oder gesammelt. Sie werden vorab durch das Symbol \"*\" mit einem Sternchen darauf hingewiesen, ob die Angaben, die Sie der Betreibergesellschaft im Rahmen der Erhebung auf der Website mitteilen m\u00fcssen, fakultativ oder obligatorisch sind. Die Betreiberin erhebt und verarbeitet Ihre personenbezogenen Daten ausschlie\u00dflich zu den in diesen rechtlichen Hinweisen beschriebenen Zwecken.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Verh\u00e4ltnism\u00e4\u00dfigkeit und Relevanz :<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Betreibergesellschaft sammelt und verarbeitet nur die personenbezogenen Daten, die f\u00fcr die ordnungsgem\u00e4\u00dfe Bearbeitung Ihrer Anfrage oder f\u00fcr die Anpassung der Ihnen angebotenen Dienste erforderlich sind.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Zeit f\u00fcr die Datenspeicherung :<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Betreibergesellschaft speichert Ihre personenbezogenen Daten nur so lange, wie es f\u00fcr die Verarbeitung gem\u00e4\u00df den Bestimmungen des geltenden Rechts erforderlich ist.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Sicherheit und Datenschutz :<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Betreibergesellschaft verpflichtet sich, die notwendigen Ma\u00dfnahmen zu ergreifen, um die Vertraulichkeit der Daten zu gew\u00e4hrleisten und sie nicht an unbefugte Dritte weiterzugeben.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Wir k\u00f6nnen Ihre personenbezogenen Daten an lokale Beh\u00f6rden weitergeben, wenn dies gesetzlich vorgeschrieben ist oder im Rahmen einer Untersuchung und in \u00dcbereinstimmung mit den lokalen Vorschriften geschieht.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Wie die meisten Websites werden bestimmte Informationen automatisch \u00fcber ein Protokoll aufgezeichnet. Zu diesen Informationen geh\u00f6ren Protokolladressen (IP-Adresse), Typ des verwendeten Browsers, Internetdienstanbieter, Verweis- und Endseiten, Betriebssystem, Datum, Zeit und Clickstream-Daten.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Cookies speichern keine Informationen, die von den Nutzern w\u00e4hrend einer Online-Buchung oder bei der Registrierung eines Kundenkontos angegeben werden. Cookies identifizieren eher Ihren Browser als Sie selbst und k\u00f6nnen f\u00fcr sich allein nicht ausreichen, um Ihre Identit\u00e4t zu enth\u00fcllen.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Wahrung Ihrer Rechte :<\/span><\/p><p class=\"p1\"><span class=\"s1\">Sie werden \u00fcber Ihr Recht auf Auskunft, Zugang, Berichtigung und Widerspruch aus legitimen Gr\u00fcnden sowie \u00fcber Ihr Recht auf Widerspruch gegen kommerzielle Werbung gem\u00e4\u00df den Bestimmungen des Gesetzes Nr. 78-17 vom 6. Januar 1978 informiert.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Rechte auf Zugang, Berichtigung und Widerspruch :<\/span><\/p><p class=\"p1\"><span class=\"s1\">Gem\u00e4\u00df dem Gesetz Nr. 78-17 vom 6. Januar 1978 \u00fcber Informatik, Dateien und Freiheiten haben Sie auf einfache schriftliche Anfrage hin ein Recht auf Zugang und Berichtigung der Sie betreffenden Informationen.<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Sie k\u00f6nnen auch aus legitimen Gr\u00fcnden gegen die Verarbeitung der Sie betreffenden Daten Widerspruch einlegen.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Um eines dieser Rechte auszu\u00fcben und Informationen \u00fcber Sie zu erhalten, wenden Sie sich einfach an die Betreibergesellschaft, deren Kontaktdaten am Anfang dieses Impressums zug\u00e4nglich sind.<\/span><\/p><p class=\"p2\"><span class=\"s1\">COOKIES<\/span><\/p><p class=\"p1\"><span class=\"s1\">Bei der Konsultation der Website k\u00f6nnen bestimmte Informationen \u00fcber die Navigation Ihres Terminals in Dateien mit der Bezeichnung \"Cookies\" gespeichert werden, die auf Ihrem Terminal installiert werden, vorbehaltlich der Wahl, die Sie bez\u00fcglich der Cookies getroffen haben und die Sie jederzeit \u00e4ndern k\u00f6nnen.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Ein Cookie ist eine kleine Textdatei, die in einem bestimmten Bereich der Festplatte Ihres Endger\u00e4ts gespeichert wird, wenn Sie mithilfe Ihrer Navigationssoftware einen Online-Dienst aufrufen. Sie erm\u00f6glicht es ihrem Emittenten, das Terminal, in dem sie gespeichert ist, w\u00e4hrend der G\u00fcltigkeits- oder Speicherdauer des Cookies zu identifizieren.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Cookies, die die Betreibergesellschaft ausstellt, werden f\u00fcr die nachfolgend beschriebenen Zwecke verwendet, und zwar w\u00e4hrend der G\u00fcltigkeitsdauer des jeweiligen Cookies, vorbehaltlich Ihrer Wahl, die sich aus den Einstellungen Ihrer Navigationssoftware ergibt, die Sie bei Ihrem Besuch der Website verwenden und deren Parametrierung Sie jederzeit \u00e4ndern k\u00f6nnen.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Cookies von Partnerunternehmen (Drittanbieter-Cookies) k\u00f6nnen \u00fcber die Seiten der Website auf Ihrem Computer platziert werden.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Nur der Emittent eines Cookies kann die darin enthaltenen Informationen lesen oder \u00e4ndern.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Auf der Website werden verschiedene Arten von Cookies verwendet, die unterschiedlichen Zwecken dienen. Einige sind notwendig, damit Sie die Website nutzen k\u00f6nnen.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Analytische Cookies<\/span><\/p><p class=\"p1\"><span class=\"s1\">Hierbei handelt es sich um Cookies, die es der Betreibergesellschaft erm\u00f6glichen :<\/span><\/p><ul class=\"ul1\"><li class=\"li4\"><span class=\"s1\">Statistiken und verschiedene Elemente, aus denen sich die Website zusammensetzt (besuchte Rubriken und Inhalte, Verl\u00e4ufe), zu erstellen, um das angebotene Surferlebnis zu verbessern;<\/span><\/li><li class=\"li4\"><span class=\"s1\">die Gesamtzahl der von ihr auf ihren Werbefl\u00e4chen angezeigten Werbeanzeigen zu erfassen, diese Werbeanzeigen zu identifizieren, die Anzahl der Anzeigen, die Anzahl der Klicks und die Navigationsinformationen.<\/span><\/li><\/ul><p class=\"p1\"><span class=\"s5\">Beispiel f\u00fcr analytische Cookies<\/span><\/p><ul class=\"ul1\"><li class=\"li4\"><span class=\"s1\">_ga Analytics: Aufzeichnung von Navigationsdaten<\/span><\/li><li class=\"li4\"><span class=\"s1\">__utm Analytics: Aufzeichnung von Navigationsdaten<\/span><\/li><li class=\"li4\"><span class=\"s1\">_gac Campaign: Aufzeichnung der Navigationsdaten von Werbekampagnen<\/span><\/li><\/ul><p class=\"p3\"><span class=\"s1\">Cookies und Plug-ins von sozialen Netzwerken (Social Buttons)<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Betreibergesellschaft kann auf der Website Tools einbinden, mit denen Sie Inhalte mit anderen Personen teilen k\u00f6nnen oder mit denen Sie anderen Personen Ihre Konsultation oder Ihre Meinung zu einem Inhalt auf unserer Website mitteilen k\u00f6nnen. Dies gilt insbesondere f\u00fcr die Schaltfl\u00e4chen \"Teilen\", \"Gef\u00e4llt mir\", die von sozialen Netzwerken wie Facebook, Twitter usw. stammen.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Das Betreiberunternehmen hat keine Kontrolle \u00fcber den Prozess, den die sozialen Netzwerke bei der Sammlung von Informationen anwenden.<\/span><\/p><ul class=\"ul1\"><li class=\"li4\"><span class=\"s1\">Facebook Connect: Anmelden mithilfe des eigenen Facebook-Kontos<\/span><\/li><li class=\"li4\"><span class=\"s1\">Facebook Social Graph: Teilen der Seite auf Facebook<\/span><\/li><li class=\"li4\"><span class=\"s1\">Pinterest: Teilen der Seite auf Pinterest<\/span><\/li><li class=\"li4\"><span class=\"s1\">Linkedin: Teilen der Seite auf Linkedin<\/span><\/li><li class=\"li4\"><span class=\"s1\">Instagram: Teilen der Seite auf Instagram<\/span><\/li><\/ul><p class=\"p3\"><span class=\"s1\">Cookies und Maschinenkennungen zum Zweck der sicheren Transaktionen<\/span><\/p><p class=\"p1\"><span class=\"s1\">Wir informieren Sie, dass die Betreibergesellschaft oder ihre in ihrem Auftrag handelnden Dienstleister bei Ihrer Bestellung Cookies hinterlegen oder Informationen \u00fcber Ihr Endger\u00e4t sammeln k\u00f6nnen, insbesondere Informationen (technische Sicherheitsattribute), die f\u00fcr die Erkennung von Ger\u00e4ten (Computer, Tablet oder Mobiltelefon) erforderlich sind, um die Identifizierung Ihres Ger\u00e4ts zum Zwecke der sicheren Abwicklung von Transaktionen in Ihrem Interesse zu erm\u00f6glichen.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Werbe-Cookies<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Werbeinhalte (Grafiken, Animationen, Videos usw.), die auf den Werbefl\u00e4chen der Betreibergesellschaft verbreitet werden, k\u00f6nnen Cookies enthalten, die von Dritten ausgegeben werden und es erm\u00f6glichen, w\u00e4hrend der G\u00fcltigkeitsdauer der Cookies die Klicks zu z\u00e4hlen und Ihnen die Werbung anzubieten, die Ihrem Surfverhalten, Ihren Interessen und Vorlieben am besten entspricht.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Ablehnung von Werbe-Cookies hat keine Auswirkungen auf die Nutzung der Website und f\u00fchrt auch nicht dazu, dass keine Werbung mehr auf der Website oder im Internet angezeigt wird. Dies hat lediglich zur Folge, dass Ihnen Werbung angezeigt wird, die nicht auf Ihre Interessen oder Vorlieben eingeht.<\/span><\/p><p class=\"p1\"><span class=\"s1\">Diese Cookies h\u00e4ngen haupts\u00e4chlich von den Werbeagenturen ab. Wir k\u00f6nnen sie nicht vollst\u00e4ndig auflisten:<\/span><\/p><ul class=\"ul1\"><li class=\"li4\"><span class=\"s1\">AdWords: Kauf von gesponserten Schl\u00fcsselw\u00f6rtern, die bei Google angezeigt werden<\/span><\/li><li class=\"li4\"><span class=\"s1\">Facebook Custom Audience<\/span><\/li><li class=\"li4\"><span class=\"s1\">gezielte Werbung: Aufzeichnung des Surfverlaufs<\/span><\/li><\/ul><p class=\"p3\"><span class=\"s1\">Zielgerichtete Werbung<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Website kann Cookies enthalten, die von Dritten (Agenturen und Werbetools) ausgegeben werden und es diesen erm\u00f6glichen, w\u00e4hrend der G\u00fcltigkeitsdauer des Cookies Navigationsdaten \u00fcber die Ger\u00e4te zu sammeln, die sich mit unseren Websites verbinden, aber auch Ihnen Werbeinhalte anzubieten, die Ihrem vorherigen Surfen auf der Website entsprechen k\u00f6nnten.<\/span><\/p><p class=\"p1\"><span class=\"s1\">In keinem Fall erlaubt diese Datenerhebung diesen Anbietern, Sie pers\u00f6nlich zu identifizieren. Ihr Name, Vorname, Benutzername, Ihre Postanschrift, E-Mail-Adresse und Ihr Passwort werden unter keinen Umst\u00e4nden ohne Ihre vorherige ausdr\u00fcckliche Zustimmung an Dritte weitergegeben.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Ihre Wahlm\u00f6glichkeiten in Bezug auf Cookies<\/span><\/p><p class=\"p1\"><span class=\"s1\">Es stehen Ihnen mehrere M\u00f6glichkeiten zur Verf\u00fcgung, um Cookies zu verwalten. Alle Einstellungen, die Sie vornehmen k\u00f6nnen, k\u00f6nnen Ihre Navigation im Internet und Ihre Zugangsbedingungen zu bestimmten Diensten, die die Verwendung von Cookies erfordern, ver\u00e4ndern.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Die Wahlm\u00f6glichkeiten, die Ihnen Ihre Browser-Software bietet<\/span><\/p><p class=\"p1\"><span class=\"s1\">Sie k\u00f6nnen Ihren Internetbrowser (Google Chrome, Internet Explorer, Mozilla Firefox usw.) so anpassen, dass Cookies in Ihrem Endger\u00e4t gespeichert oder im Gegenteil abgelehnt werden.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Die Ablehnung von Cookies<\/span><\/p><p class=\"p1\"><span class=\"s1\">Wenn Sie die Speicherung von Cookies ablehnen, stehen Ihnen bestimmte Funktionen nicht mehr zur Verf\u00fcgung, z. B. die Identifizierung\/Verbindung zu Ihrem pers\u00f6nlichen Bereich, die Personalisierung Ihrer Navigation (z. B. Wahl der bevorzugten Sprache).<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Betreibergesellschaft \u00fcbernimmt keine Verantwortung f\u00fcr die Folgen, die mit dem beeintr\u00e4chtigten Funktionieren ihrer Dienste und Funktionen aufgrund der Ablehnung des Cookies verbunden sind.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Wie \u00fcben Sie Ihre Wahlm\u00f6glichkeiten aus, je nachdem, welchen Browser Sie verwenden?<\/span><\/p><p class=\"p1\"><span class=\"s1\">F\u00fcr die Verwaltung von Cookies und Ihrer Wahlm\u00f6glichkeiten ist die Konfiguration jedes Browsers unterschiedlich. Sie wird im Hilfemen\u00fc Ihres Browsers beschrieben, in dem Sie erfahren, wie Sie Ihre W\u00fcnsche bez\u00fcglich der Cookies \u00e4ndern k\u00f6nnen.<\/span><\/p><p class=\"p1\"><span class=\"s5\">F\u00fcr Internet Explorer\u2122 :<\/span><\/p><p class=\"p1\"><span class=\"s1\"><i>https:\/\/support.microsoft.com\/fr-fr\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/i><\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">oder<\/span><\/p><p class=\"p1\"><span class=\"s1\">Klicken Sie im Internet Explorer auf die Schaltfl\u00e4che Extras und dann auf Internetoptionen. Klicken Sie auf der Registerkarte Allgemein unter Browserverlauf auf Einstellungen. Klicken Sie auf die Schaltfl\u00e4che Dateien anzeigen. Klicken Sie auf die Spalten\u00fcberschrift Name, um alle Dateien in alphabetischer Reihenfolge zu sortieren, und gehen Sie dann die Liste durch, bis Sie Dateien sehen, die mit dem Pr\u00e4fix \"Cookie\" beginnen (alle Cookies haben dieses Pr\u00e4fix und enthalten normalerweise den Namen der Website, die das Cookie erstellt hat). W\u00e4hlen Sie den\/die Cookie(s) mit dem Namen der Betreibergesellschaft aus und l\u00f6schen Sie ihn\/sie. Schlie\u00dfen Sie das Fenster mit der Dateiliste und klicken Sie zweimal auf OK, um zum Internet Explorer zur\u00fcckzukehren.<\/span><\/p><p class=\"p1\"><span class=\"s5\">F\u00fcr Safari\u2122 :<\/span><\/p><p class=\"p1\"><span class=\"s1\"><i>https:\/\/support.apple.com\/?path=Safari\/3.0\/fr\/9277.html<\/i><\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Oder<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">W\u00e4hlen Sie in Ihrem Browser das Men\u00fc Bearbeiten &gt; Einstellungen. Klicken Sie auf Sicherheit. Klicken Sie auf Cookies anzeigen. W\u00e4hlen Sie die Cookies aus, die den Namen der Betreibergesellschaft enthalten, und klicken Sie auf L\u00f6schen oder Alle l\u00f6schen. Nachdem Sie die Cookies gel\u00f6scht haben, klicken Sie auf Fertig.<\/span><\/p><p class=\"p1\"><span class=\"s5\">F\u00fcr Chrome\u2122 :<\/span><\/p><p class=\"p1\"><span class=\"s1\"><i>https:\/\/support.google.com\/chrome\/answer\/95647?hl=fr&amp;hlrm=en<\/i><\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Oder<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">\u00d6ffnen Sie Google Chrome. Klicken Sie in der Symbolleiste des Browsers auf Mehr. Bewegen Sie Ihren Cursor auf Mehr Tools und klicken Sie dann auf Browserdaten l\u00f6schen. Aktivieren Sie im Fenster \"Browserdaten l\u00f6schen\" die Kontrollk\u00e4stchen Cookies und Daten von anderen Websites oder Plug-ins und Bilder und Cache-Dateien. Verwenden Sie das Men\u00fc oben, um die Menge der Daten auszuw\u00e4hlen, die Sie l\u00f6schen m\u00f6chten. W\u00e4hlen Sie Von Anfang an, um alles zu l\u00f6schen. Klicken Sie auf Browserdaten l\u00f6schen.<\/span><\/p><p class=\"p1\"><span class=\"s5\">F\u00fcr Firefox\u2122 :<\/span><\/p><p class=\"p1\"><span class=\"s1\"><i>https:\/\/support.mozilla.org\/fr\/kb\/activer-desactiver-cookies-preferences<\/i><\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Oder<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Gehen Sie auf die Registerkarte \"Extras\" des Browsers und w\u00e4hlen Sie dann das Men\u00fc \"Optionen\". Im angezeigten Fenster w\u00e4hlen Sie \"Datenschutz\" und klicken auf \"Bestimmte Cookies l\u00f6schen\". Suchen Sie nach Dateien, die den Namen der Betreibergesellschaft enthalten. W\u00e4hlen Sie diese aus und l\u00f6schen Sie sie.<\/span><\/p><p class=\"p3\"><span class=\"s1\">Weitere Informationen zu Cookies<\/span><\/p><p class=\"p1\"><span class=\"s1\">Die Betreibergesellschaft l\u00e4dt Sie ein, die Website der CNIL unter der folgenden Adresse zu besuchen:\u00a0<i>https:\/\/www.cnil.fr\/fr\/cookies-les-outils-pour-les-maitriser<\/i><\/span><\/p><p class=\"p3\"><span class=\"s1\">Anrufung des Verbraucherombudsmanns<\/span><\/p><p class=\"p1\"><span class=\"s1\">Gem\u00e4\u00df Artikel L. 616-1 und R. 111-1 6\u00b0 des Verbraucherschutzgesetzes hat der Kunde das Recht, sich kostenlos an den Ombudsmann f\u00fcr Tourismus und Reisen zu wenden, dessen Kontaktdaten derzeit wie folgt lauten:<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">Ombudsmann f\u00fcr Tourismus und Reisen,<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">MTV Vermittlung Tourismus Reisen<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">BP 80 303<\/span><span class=\"s2\"><br \/><\/span><span class=\"s1\">75823 Paris Cedex 17<\/span><\/p><p class=\"p5\"><span class=\"s6\">Gestaltung der Website<\/span><span class=\"s7\"><br \/><a href=\"https:\/\/hotel-webdesign.com\/\"><span class=\"s8\">Erstellung von Hotelseiten<\/span><\/a><br \/><a href=\"https:\/\/www.france-webdesign.com\/\"><span class=\"s8\">Erstellung von professionellen Websites<\/span><\/a><br \/><\/span><span class=\"s6\">128, rue de la bo\u00e9tie<\/span><span class=\"s7\"><br \/><\/span><span class=\"s6\">75008 PARIS<\/span><\/p><p class=\"p5\"><span class=\"s6\">\u00a0<a href=\"https:\/\/hotel-webdesign.com\/\"><span class=\"s9\">Erstellung einer Hotel-Restaurant-Website<\/span><\/a>\u00a0|\u00a0<a href=\"https:\/\/hotel-webdesign.com\/\"><span class=\"s9\">Hotel Web Design<\/span><\/a> |\u00a0<a href=\"https:\/\/www.france-webdesign.com\/\"><span class=\"s9\">Web Design Agentur<\/span><\/a>\u00a0|<a href=\"https:\/\/w-maintenance.pro\/\"><span class=\"s9\">WordPress-Support<\/span><\/a>\u00a0|\u00a0\u00a0<a href=\"https:\/\/w-maintenance.pro\/\"><span class=\"s9\">WordPress-Wartung<\/span><\/a>\u00a0|\u00a0<a href=\"https:\/\/www.referencement-annuaire.fr\/\"><span class=\"s9\">Referenzierung Unternehmen<\/span><\/a> | <a href=\"https:\/\/hotel-webdesign.com\/creation-site-auberge\" target=\"_blank\" rel=\"noopener\">Erstellung einer Website f\u00fcr das Gasthaus\u00a0<\/a><\/span><\/p><p class=\"p7\"><span class=\"s2\">\u00a0<\/span><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mentions L\u00e9gales Responsable de la publication: Mme LEMOINE Raison sociale de la soci\u00e9t\u00e9 exploitante : RELAIS MANDEREN SARLNum\u00e9ro individuel d\u2019identification de TVA : FR01919081851Num\u00e9ro de Siret :91908185100017Capital Social: 5000\u20ac INFORMATIQUE ET LIBERT\u00c9Tout utilisateur ayant d\u00e9pos\u00e9 des informations directement ou indirectement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4309","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/pages\/4309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/comments?post=4309"}],"version-history":[{"count":3,"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/pages\/4309\/revisions"}],"predecessor-version":[{"id":5571,"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/pages\/4309\/revisions\/5571"}],"wp:attachment":[{"href":"https:\/\/relaismanderen.com\/de\/wp-json\/wp\/v2\/media?parent=4309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}